{"id":8976,"date":"2025-10-01T21:21:45","date_gmt":"2025-10-02T00:21:45","guid":{"rendered":"https:\/\/maetinganoticias.com\/?p=8976"},"modified":"2025-10-01T21:21:45","modified_gmt":"2025-10-02T00:21:45","slug":"prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado","status":"publish","type":"post","link":"https:\/\/maetinganoticias.com\/index.php\/2025\/10\/01\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\/","title":{"rendered":"Prefeito Phellipe Brito prestigia solenidade de passagem de comando do 24\u00ba BPM em Brumado"},"content":{"rendered":"\n<p class=\"p3 wp-block-paragraph\">O prefeito de Itua\u00e7u, Phellipe Brito, esteve presente na manh\u00e3 desta quarta-feira (01\/10) na C\u00e2mara de Vereadores de Brumado, onde aconteceu a solenidade de passagem de comando do 24\u00ba Batalh\u00e3o de Pol\u00edcia Militar. <\/p>\n\n\n\n<p class=\"p3 wp-block-paragraph\">O evento reuniu autoridades militares, representantes pol\u00edticos, entidades civis e membros da comunidade.<\/p>\n\n\n\n<p class=\"p3 wp-block-paragraph\">Na cerim\u00f4nia, o Tenente Coronel PM Eduardo Viana Moreira J\u00fanior deixou o comando do batalh\u00e3o e assumir\u00e1 agora a lideran\u00e7a do 9\u00ba Batalh\u00e3o de Ensino, Instru\u00e7\u00e3o e Capacita\u00e7\u00e3o (9\u00ba BEIC), sediado em Vit\u00f3ria da Conquista. Em seu lugar, passou a responder pelo 24\u00ba BPM o Tenente Coronel PM Jocev\u00e3 Lima Oliveira, que assume a miss\u00e3o de dar continuidade \u00e0s a\u00e7\u00f5es de seguran\u00e7a p\u00fablica desenvolvidas pela corpora\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"p3 wp-block-paragraph\">O ato foi presidido pelo Coronel PM Paulo Henrique Rocha Guimar\u00e3es, Comandante do CPR-Sudoeste.<\/p>\n\n\n\n<p class=\"p3 wp-block-paragraph\">O prefeito Phellipe Brito ressaltou a import\u00e2ncia da Pol\u00edcia Militar para toda a regi\u00e3o:<\/p>\n\n\n\n<p class=\"p3 wp-block-paragraph\"><strong><em>\u201cA seguran\u00e7a p\u00fablica \u00e9 fundamental para o desenvolvimento dos nossos munic\u00edpios. \u00c9 uma honra poder acompanhar este momento hist\u00f3rico e reafirmar nosso compromisso em trabalhar lado a lado com as for\u00e7as de seguran\u00e7a para garantir mais tranquilidade \u00e0 nossa popula\u00e7\u00e3o<\/em><\/strong>\u201d, destacou.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"828\" height=\"616\" src=\"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2025\/10\/img_5005.jpg\" class=\"wp-image-8975\" srcset=\"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2025\/10\/img_5005.jpg 828w, https:\/\/maetinganoticias.com\/wp-content\/uploads\/2025\/10\/img_5005-300x223.jpg 300w, https:\/\/maetinganoticias.com\/wp-content\/uploads\/2025\/10\/img_5005-768x571.jpg 768w, https:\/\/maetinganoticias.com\/wp-content\/uploads\/2025\/10\/img_5005-565x420.jpg 565w, https:\/\/maetinganoticias.com\/wp-content\/uploads\/2025\/10\/img_5005-80x60.jpg 80w, https:\/\/maetinganoticias.com\/wp-content\/uploads\/2025\/10\/img_5005-150x112.jpg 150w, https:\/\/maetinganoticias.com\/wp-content\/uploads\/2025\/10\/img_5005-485x360.jpg 485w, https:\/\/maetinganoticias.com\/wp-content\/uploads\/2025\/10\/img_5005-696x518.jpg 696w, https:\/\/maetinganoticias.com\/wp-content\/uploads\/2025\/10\/img_5005-265x198.jpg 265w\" sizes=\"auto, (max-width: 828px) 100vw, 828px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito de Itua\u00e7u, Phellipe Brito, esteve presente na manh\u00e3 desta quarta-feira (01\/10) na C\u00e2mara de Vereadores de Brumado, onde aconteceu a solenidade de passagem de comando do 24\u00ba Batalh\u00e3o de Pol\u00edcia Militar. O evento reuniu autoridades militares, representantes pol\u00edticos, entidades civis e membros da comunidade. Na cerim\u00f4nia, o Tenente Coronel PM Eduardo Viana Moreira [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8974,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[42],"tags":[],"class_list":["post-8976","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brumado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prefeito Phellipe Brito prestigia solenidade de passagem de comando do 24\u00ba BPM em Brumado - Maetinga Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maetinganoticias.com\/index.php\/2025\/10\/01\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prefeito Phellipe Brito prestigia solenidade de passagem de comando do 24\u00ba BPM em Brumado - Maetinga Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"O prefeito de Itua\u00e7u, Phellipe Brito, esteve presente na manh\u00e3 desta quarta-feira (01\/10) na C\u00e2mara de Vereadores de Brumado, onde aconteceu a solenidade de passagem de comando do 24\u00ba Batalh\u00e3o de Pol\u00edcia Militar. O evento reuniu autoridades militares, representantes pol\u00edticos, entidades civis e membros da comunidade. Na cerim\u00f4nia, o Tenente Coronel PM Eduardo Viana Moreira [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maetinganoticias.com\/index.php\/2025\/10\/01\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\/\" \/>\n<meta property=\"og:site_name\" content=\"Maetinga Not\u00edcias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-02T00:21:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2025\/10\/img_5004.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"828\" \/>\n\t<meta property=\"og:image:height\" content=\"1132\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maetinga Not\u00edcias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maetinga Not\u00edcias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/10\\\/01\\\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/10\\\/01\\\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\\\/\"},\"author\":{\"name\":\"Maetinga Not\u00edcias\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#\\\/schema\\\/person\\\/968cf95e67a6810fc7fb35bbc9016962\"},\"headline\":\"Prefeito Phellipe Brito prestigia solenidade de passagem de comando do 24\u00ba BPM em Brumado\",\"datePublished\":\"2025-10-02T00:21:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/10\\\/01\\\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\\\/\"},\"wordCount\":215,\"publisher\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/10\\\/01\\\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/img_5004.jpg\",\"articleSection\":[\"Brumado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/10\\\/01\\\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\\\/\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/10\\\/01\\\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\\\/\",\"name\":\"Prefeito Phellipe Brito prestigia solenidade de passagem de comando do 24\u00ba BPM em Brumado - Maetinga Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/10\\\/01\\\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/10\\\/01\\\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/img_5004.jpg\",\"datePublished\":\"2025-10-02T00:21:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/10\\\/01\\\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/10\\\/01\\\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/10\\\/01\\\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/img_5004.jpg\",\"contentUrl\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/img_5004.jpg\",\"width\":828,\"height\":1132},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/10\\\/01\\\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/maetinganoticias.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prefeito Phellipe Brito prestigia solenidade de passagem de comando do 24\u00ba BPM em Brumado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#website\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/\",\"name\":\"Maetinga Not\u00edcias\",\"description\":\"A Voz do Interior Baiano!\",\"publisher\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maetinganoticias.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#organization\",\"name\":\"Maetinga Not\u00edcias\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-cropped-cropped-BUSINESS-3-42-1.png\",\"contentUrl\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-cropped-cropped-BUSINESS-3-42-1.png\",\"width\":485,\"height\":109,\"caption\":\"Maetinga Not\u00edcias\"},\"image\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#\\\/schema\\\/person\\\/968cf95e67a6810fc7fb35bbc9016962\",\"name\":\"Maetinga Not\u00edcias\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g\",\"caption\":\"Maetinga Not\u00edcias\"},\"description\":\"A voz do Interior Baiano!\",\"sameAs\":[\"https:\\\/\\\/maetinganoticias.com\",\"https:\\\/\\\/www.instagram.com\\\/blogmaetinganoticias\\\/\"],\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/author\\\/carlosvianna13\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prefeito Phellipe Brito prestigia solenidade de passagem de comando do 24\u00ba BPM em Brumado - Maetinga Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maetinganoticias.com\/index.php\/2025\/10\/01\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\/","og_locale":"pt_BR","og_type":"article","og_title":"Prefeito Phellipe Brito prestigia solenidade de passagem de comando do 24\u00ba BPM em Brumado - Maetinga Not\u00edcias","og_description":"O prefeito de Itua\u00e7u, Phellipe Brito, esteve presente na manh\u00e3 desta quarta-feira (01\/10) na C\u00e2mara de Vereadores de Brumado, onde aconteceu a solenidade de passagem de comando do 24\u00ba Batalh\u00e3o de Pol\u00edcia Militar. O evento reuniu autoridades militares, representantes pol\u00edticos, entidades civis e membros da comunidade. Na cerim\u00f4nia, o Tenente Coronel PM Eduardo Viana Moreira [&hellip;]","og_url":"https:\/\/maetinganoticias.com\/index.php\/2025\/10\/01\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\/","og_site_name":"Maetinga Not\u00edcias","article_published_time":"2025-10-02T00:21:45+00:00","og_image":[{"width":828,"height":1132,"url":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2025\/10\/img_5004.jpg","type":"image\/jpeg"}],"author":"Maetinga Not\u00edcias","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Maetinga Not\u00edcias","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/maetinganoticias.com\/index.php\/2025\/10\/01\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\/#article","isPartOf":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2025\/10\/01\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\/"},"author":{"name":"Maetinga Not\u00edcias","@id":"https:\/\/maetinganoticias.com\/#\/schema\/person\/968cf95e67a6810fc7fb35bbc9016962"},"headline":"Prefeito Phellipe Brito prestigia solenidade de passagem de comando do 24\u00ba BPM em Brumado","datePublished":"2025-10-02T00:21:45+00:00","mainEntityOfPage":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2025\/10\/01\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\/"},"wordCount":215,"publisher":{"@id":"https:\/\/maetinganoticias.com\/#organization"},"image":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2025\/10\/01\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\/#primaryimage"},"thumbnailUrl":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2025\/10\/img_5004.jpg","articleSection":["Brumado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/maetinganoticias.com\/index.php\/2025\/10\/01\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\/","url":"https:\/\/maetinganoticias.com\/index.php\/2025\/10\/01\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\/","name":"Prefeito Phellipe Brito prestigia solenidade de passagem de comando do 24\u00ba BPM em Brumado - Maetinga Not\u00edcias","isPartOf":{"@id":"https:\/\/maetinganoticias.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2025\/10\/01\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\/#primaryimage"},"image":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2025\/10\/01\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\/#primaryimage"},"thumbnailUrl":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2025\/10\/img_5004.jpg","datePublished":"2025-10-02T00:21:45+00:00","breadcrumb":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2025\/10\/01\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maetinganoticias.com\/index.php\/2025\/10\/01\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maetinganoticias.com\/index.php\/2025\/10\/01\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\/#primaryimage","url":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2025\/10\/img_5004.jpg","contentUrl":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2025\/10\/img_5004.jpg","width":828,"height":1132},{"@type":"BreadcrumbList","@id":"https:\/\/maetinganoticias.com\/index.php\/2025\/10\/01\/prefeito-phellipe-brito-prestigia-solenidade-de-passagem-de-comando-do-24o-bpm-em-brumado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/maetinganoticias.com\/"},{"@type":"ListItem","position":2,"name":"Prefeito Phellipe Brito prestigia solenidade de passagem de comando do 24\u00ba BPM em Brumado"}]},{"@type":"WebSite","@id":"https:\/\/maetinganoticias.com\/#website","url":"https:\/\/maetinganoticias.com\/","name":"Maetinga Not\u00edcias","description":"A Voz do Interior Baiano!","publisher":{"@id":"https:\/\/maetinganoticias.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maetinganoticias.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/maetinganoticias.com\/#organization","name":"Maetinga Not\u00edcias","url":"https:\/\/maetinganoticias.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maetinganoticias.com\/#\/schema\/logo\/image\/","url":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/07\/cropped-cropped-cropped-cropped-BUSINESS-3-42-1.png","contentUrl":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/07\/cropped-cropped-cropped-cropped-BUSINESS-3-42-1.png","width":485,"height":109,"caption":"Maetinga Not\u00edcias"},"image":{"@id":"https:\/\/maetinganoticias.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/maetinganoticias.com\/#\/schema\/person\/968cf95e67a6810fc7fb35bbc9016962","name":"Maetinga Not\u00edcias","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g","caption":"Maetinga Not\u00edcias"},"description":"A voz do Interior Baiano!","sameAs":["https:\/\/maetinganoticias.com","https:\/\/www.instagram.com\/blogmaetinganoticias\/"],"url":"https:\/\/maetinganoticias.com\/index.php\/author\/carlosvianna13\/"}]}},"_links":{"self":[{"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/8976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=8976"}],"version-history":[{"count":1,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/8976\/revisions"}],"predecessor-version":[{"id":8977,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/8976\/revisions\/8977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/media\/8974"}],"wp:attachment":[{"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=8976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=8976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=8976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}