{"id":7689,"date":"2025-03-16T18:03:15","date_gmt":"2025-03-16T21:03:15","guid":{"rendered":"https:\/\/maetinganoticias.com\/?p=7689"},"modified":"2025-03-16T18:03:16","modified_gmt":"2025-03-16T21:03:16","slug":"homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado","status":"publish","type":"post","link":"https:\/\/maetinganoticias.com\/index.php\/2025\/03\/16\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\/","title":{"rendered":"Homem atropela policiais militares ao tentar fugir de blitz em Brumado"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\" id=\"isPasted\">Na noite deste s\u00e1bado (15), um homem foi detido ap\u00f3s furar um bloqueio policial e atropelar dois policiais militares durante uma blitz realizada pela Companhia de Emprego T\u00e1tico Operacional (CETO), Radiopatrulha (RP) e motopatrulhamento Extra, em frente \u00e0 Igreja Matriz, no centro de\u00a0Brumado\u00a0(BA). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"isPasted\">De acordo com o boletim de ocorr\u00eancia registrado na 1\u00aa Delegacia Territorial de Brumado, o suspeito de 18 anos, conduzia uma motocicleta sem placa quando desobedeceu \u00e0 ordem de parada e colidiu contra um Aspirante e um Cabo que atuavam na opera\u00e7\u00e3o. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"isPasted\">Ap\u00f3s o impacto, o suspeito foi contido e encaminhado, junto com os policiais feridos, ao Hospital Municipal de Brumado para atendimento m\u00e9dico. Durante a verifica\u00e7\u00e3o, foi constatado que a motocicleta utilizada pelo indiv\u00edduo possu\u00eda restri\u00e7\u00e3o de furto\/roubo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"isPasted\"> Al\u00e9m disso, um Soldado, que tamb\u00e9m participou da ocorr\u00eancia, percebeu que um fuzil IMBEL calibre 5.56, pertencente \u00e0 corpora\u00e7\u00e3o, teve danos em seu aparelho durante o incidente. O suspeito e o ve\u00edculo foram encaminhados \u00e0 delegacia para a ado\u00e7\u00e3o das medidas cab\u00edveis. O caso segue sob investiga\u00e7\u00e3o da\u00a0Pol\u00edcia Civil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na noite deste s\u00e1bado (15), um homem foi detido ap\u00f3s furar um bloqueio policial e atropelar dois policiais militares durante uma blitz realizada pela Companhia de Emprego T\u00e1tico Operacional (CETO), Radiopatrulha (RP) e motopatrulhamento Extra, em frente \u00e0 Igreja Matriz, no centro de\u00a0Brumado\u00a0(BA). De acordo com o boletim de ocorr\u00eancia registrado na 1\u00aa Delegacia Territorial [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7690,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[42],"tags":[],"class_list":["post-7689","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brumado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Homem atropela policiais militares ao tentar fugir de blitz em Brumado - Maetinga Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maetinganoticias.com\/index.php\/2025\/03\/16\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Homem atropela policiais militares ao tentar fugir de blitz em Brumado - Maetinga Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"Na noite deste s\u00e1bado (15), um homem foi detido ap\u00f3s furar um bloqueio policial e atropelar dois policiais militares durante uma blitz realizada pela Companhia de Emprego T\u00e1tico Operacional (CETO), Radiopatrulha (RP) e motopatrulhamento Extra, em frente \u00e0 Igreja Matriz, no centro de\u00a0Brumado\u00a0(BA). De acordo com o boletim de ocorr\u00eancia registrado na 1\u00aa Delegacia Territorial [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maetinganoticias.com\/index.php\/2025\/03\/16\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\/\" \/>\n<meta property=\"og:site_name\" content=\"Maetinga Not\u00edcias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-16T21:03:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-16T21:03:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-16-at-18.02.30.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"648\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maetinga Not\u00edcias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maetinga Not\u00edcias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/03\\\/16\\\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/03\\\/16\\\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\\\/\"},\"author\":{\"name\":\"Maetinga Not\u00edcias\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#\\\/schema\\\/person\\\/968cf95e67a6810fc7fb35bbc9016962\"},\"headline\":\"Homem atropela policiais militares ao tentar fugir de blitz em Brumado\",\"datePublished\":\"2025-03-16T21:03:15+00:00\",\"dateModified\":\"2025-03-16T21:03:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/03\\\/16\\\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\\\/\"},\"wordCount\":198,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/03\\\/16\\\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/WhatsApp-Image-2025-03-16-at-18.02.30.jpeg\",\"articleSection\":[\"Brumado\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/03\\\/16\\\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/03\\\/16\\\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\\\/\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/03\\\/16\\\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\\\/\",\"name\":\"Homem atropela policiais militares ao tentar fugir de blitz em Brumado - Maetinga Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/03\\\/16\\\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/03\\\/16\\\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/WhatsApp-Image-2025-03-16-at-18.02.30.jpeg\",\"datePublished\":\"2025-03-16T21:03:15+00:00\",\"dateModified\":\"2025-03-16T21:03:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/03\\\/16\\\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/03\\\/16\\\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/03\\\/16\\\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/WhatsApp-Image-2025-03-16-at-18.02.30.jpeg\",\"contentUrl\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/WhatsApp-Image-2025-03-16-at-18.02.30.jpeg\",\"width\":1000,\"height\":648,\"caption\":\"Foto - Redes Sociais\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2025\\\/03\\\/16\\\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/maetinganoticias.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Homem atropela policiais militares ao tentar fugir de blitz em Brumado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#website\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/\",\"name\":\"Maetinga Not\u00edcias\",\"description\":\"A Voz do Interior Baiano!\",\"publisher\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maetinganoticias.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#organization\",\"name\":\"Maetinga Not\u00edcias\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-cropped-cropped-BUSINESS-3-42-1.png\",\"contentUrl\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-cropped-cropped-BUSINESS-3-42-1.png\",\"width\":485,\"height\":109,\"caption\":\"Maetinga Not\u00edcias\"},\"image\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#\\\/schema\\\/person\\\/968cf95e67a6810fc7fb35bbc9016962\",\"name\":\"Maetinga Not\u00edcias\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g\",\"caption\":\"Maetinga Not\u00edcias\"},\"description\":\"A voz do Interior Baiano!\",\"sameAs\":[\"https:\\\/\\\/maetinganoticias.com\",\"https:\\\/\\\/www.instagram.com\\\/blogmaetinganoticias\\\/\"],\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/author\\\/carlosvianna13\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Homem atropela policiais militares ao tentar fugir de blitz em Brumado - Maetinga Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maetinganoticias.com\/index.php\/2025\/03\/16\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\/","og_locale":"pt_BR","og_type":"article","og_title":"Homem atropela policiais militares ao tentar fugir de blitz em Brumado - Maetinga Not\u00edcias","og_description":"Na noite deste s\u00e1bado (15), um homem foi detido ap\u00f3s furar um bloqueio policial e atropelar dois policiais militares durante uma blitz realizada pela Companhia de Emprego T\u00e1tico Operacional (CETO), Radiopatrulha (RP) e motopatrulhamento Extra, em frente \u00e0 Igreja Matriz, no centro de\u00a0Brumado\u00a0(BA). De acordo com o boletim de ocorr\u00eancia registrado na 1\u00aa Delegacia Territorial [&hellip;]","og_url":"https:\/\/maetinganoticias.com\/index.php\/2025\/03\/16\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\/","og_site_name":"Maetinga Not\u00edcias","article_published_time":"2025-03-16T21:03:15+00:00","article_modified_time":"2025-03-16T21:03:16+00:00","og_image":[{"width":1000,"height":648,"url":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-16-at-18.02.30.jpeg","type":"image\/jpeg"}],"author":"Maetinga Not\u00edcias","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Maetinga Not\u00edcias","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/maetinganoticias.com\/index.php\/2025\/03\/16\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\/#article","isPartOf":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2025\/03\/16\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\/"},"author":{"name":"Maetinga Not\u00edcias","@id":"https:\/\/maetinganoticias.com\/#\/schema\/person\/968cf95e67a6810fc7fb35bbc9016962"},"headline":"Homem atropela policiais militares ao tentar fugir de blitz em Brumado","datePublished":"2025-03-16T21:03:15+00:00","dateModified":"2025-03-16T21:03:16+00:00","mainEntityOfPage":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2025\/03\/16\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\/"},"wordCount":198,"commentCount":0,"publisher":{"@id":"https:\/\/maetinganoticias.com\/#organization"},"image":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2025\/03\/16\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\/#primaryimage"},"thumbnailUrl":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-16-at-18.02.30.jpeg","articleSection":["Brumado"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maetinganoticias.com\/index.php\/2025\/03\/16\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maetinganoticias.com\/index.php\/2025\/03\/16\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\/","url":"https:\/\/maetinganoticias.com\/index.php\/2025\/03\/16\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\/","name":"Homem atropela policiais militares ao tentar fugir de blitz em Brumado - Maetinga Not\u00edcias","isPartOf":{"@id":"https:\/\/maetinganoticias.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2025\/03\/16\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\/#primaryimage"},"image":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2025\/03\/16\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\/#primaryimage"},"thumbnailUrl":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-16-at-18.02.30.jpeg","datePublished":"2025-03-16T21:03:15+00:00","dateModified":"2025-03-16T21:03:16+00:00","breadcrumb":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2025\/03\/16\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maetinganoticias.com\/index.php\/2025\/03\/16\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maetinganoticias.com\/index.php\/2025\/03\/16\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\/#primaryimage","url":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-16-at-18.02.30.jpeg","contentUrl":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-16-at-18.02.30.jpeg","width":1000,"height":648,"caption":"Foto - Redes Sociais"},{"@type":"BreadcrumbList","@id":"https:\/\/maetinganoticias.com\/index.php\/2025\/03\/16\/homem-atropela-policiais-militares-ao-tentar-fugir-de-blitz-em-brumado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/maetinganoticias.com\/"},{"@type":"ListItem","position":2,"name":"Homem atropela policiais militares ao tentar fugir de blitz em Brumado"}]},{"@type":"WebSite","@id":"https:\/\/maetinganoticias.com\/#website","url":"https:\/\/maetinganoticias.com\/","name":"Maetinga Not\u00edcias","description":"A Voz do Interior Baiano!","publisher":{"@id":"https:\/\/maetinganoticias.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maetinganoticias.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/maetinganoticias.com\/#organization","name":"Maetinga Not\u00edcias","url":"https:\/\/maetinganoticias.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maetinganoticias.com\/#\/schema\/logo\/image\/","url":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/07\/cropped-cropped-cropped-cropped-BUSINESS-3-42-1.png","contentUrl":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/07\/cropped-cropped-cropped-cropped-BUSINESS-3-42-1.png","width":485,"height":109,"caption":"Maetinga Not\u00edcias"},"image":{"@id":"https:\/\/maetinganoticias.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/maetinganoticias.com\/#\/schema\/person\/968cf95e67a6810fc7fb35bbc9016962","name":"Maetinga Not\u00edcias","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g","caption":"Maetinga Not\u00edcias"},"description":"A voz do Interior Baiano!","sameAs":["https:\/\/maetinganoticias.com","https:\/\/www.instagram.com\/blogmaetinganoticias\/"],"url":"https:\/\/maetinganoticias.com\/index.php\/author\/carlosvianna13\/"}]}},"_links":{"self":[{"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/7689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=7689"}],"version-history":[{"count":2,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/7689\/revisions"}],"predecessor-version":[{"id":7692,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/7689\/revisions\/7692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/media\/7690"}],"wp:attachment":[{"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=7689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=7689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=7689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}