{"id":5328,"date":"2024-08-06T21:10:58","date_gmt":"2024-08-07T00:10:58","guid":{"rendered":"https:\/\/maetinganoticias.com\/?p=5328"},"modified":"2024-08-06T21:10:59","modified_gmt":"2024-08-07T00:10:59","slug":"brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino","status":"publish","type":"post","link":"https:\/\/maetinganoticias.com\/index.php\/2024\/08\/06\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\/","title":{"rendered":"Brasil derrota Espanha e garante lugar na final do futebol feminino"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em><strong>Sele\u00e7\u00e3o brasileira joga bem e derrota campe\u00e3s do mundo por 4 a 2<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Brasil garantiu a classifica\u00e7\u00e3o para a decis\u00e3o do torneio de futebol feminino dos Jogos Ol\u00edmpicos de Paris (Fran\u00e7a) ap\u00f3s derrotar a Espanha por 4 a 2, na tarde desta ter\u00e7a-feira (6) no est\u00e1dio Vel\u00f3drome, em Marselha, em confronto v\u00e1lido pelas semifinais da competi\u00e7\u00e3o.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1606719&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1606719&amp;o=node\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agora a sele\u00e7\u00e3o brasileira medir\u00e1 for\u00e7as com os Estados Unidos, que superaram a Alemanha por 1 a 0 na outra semifinal. A disputa pelo ouro ser\u00e1 realizada no pr\u00f3ximo s\u00e1bado (10), a partir das 12h (hor\u00e1rio de Bras\u00edlia).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A equipe comandada pelo t\u00e9cnico Arthur Elias conseguiu ficar em vantagem logo no in\u00edcio do confronto, aos 4 minutos, quando Priscila pressionou a goleira Cata Coll, a arqueira acabou chutando em cima da zagueira Irene Paredes e a bola acabou indo para o fundo do gol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Brasil mostrou maturidade a partir da\u00ed, para aproveitar a vantagem no marcador, se fechando bem na defesa e apostando em jogadas r\u00e1pidas de contra-ataque para empilhar oportunidades de marcar. De tanto tentar, a sele\u00e7\u00e3o brasileira conseguiu ampliar aos 48 minutos, quando a meio-campista Yasmim avan\u00e7ou em liberdade pela ponta esquerda e cruzou na medida para Gabi Portilho escorar de primeira.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s o intervalo a equipe comandada pelo t\u00e9cnico Arthur Elias assumiu de vez o controle da partida, criando \u00f3timas oportunidades de marcar o terceiro, com Gabi Portilho aos 3 minutos, com chute de fora da \u00e1rea de Ludmila aos 6 e com Jheniffer um minuto depois.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aos 24 minutos Hermoso ainda deu um susto no Brasil ao acertar chute da entrada da \u00e1rea que obrigou a goleira Lorena a realizar uma dif\u00edcil defesa. Mas o dia era mesmo da equipe brasileira, que encaixou um contra-ataque em velocidade um minuto depois para chegar ao terceiro. Priscila partiu em velocidade pela esquerda e, ao chegar \u00e0 \u00e1rea, rolou para Adriana, que chutou no travess\u00e3o. A bola sobrou ent\u00e3o para Gabi Portilho, que escorou de cabe\u00e7a para Adriana, que n\u00e3o perdoou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As oportunidades continuaram aparecendo de lado a lado e, de tanto tentar, a Espanha conseguiu descontar aos 39 minutos, quando Paralluelo aproveitou bola levantada na \u00e1rea por Hermoso para cabecear e vencer Lorena. Um minuto depois as atuais campe\u00e3s do mundo tiveram outra grande oportunidade de marcar, com uma finaliza\u00e7\u00e3o da entrada da \u00e1rea de Putellas que explodiu no travess\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por\u00e9m, o Brasil estava em uma jornada especial e deixou o melhor para o final. Ap\u00f3s vacilo da lateral Oihane Hern\u00e1ndez, Kerolin dominou a bola, avan\u00e7ou com muita liberdade e mostrou frieza para bater por baixo das pernas da goleira Cata Coll. A Espanha ainda voltou a marcar com Paralluelo, mas o triunfo final ficou mesmo com a sele\u00e7\u00e3o brasileira.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cr\u00e9ditos: Ag\u00eancia Brasil<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1606719&amp;o=node\" alt=\"\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1606719&amp;o=node\" alt=\"\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Sele\u00e7\u00e3o brasileira joga bem e derrota campe\u00e3s do mundo por 4 a 2 O Brasil garantiu a classifica\u00e7\u00e3o para a decis\u00e3o do torneio de futebol feminino dos Jogos Ol\u00edmpicos de Paris (Fran\u00e7a) ap\u00f3s derrotar a Espanha por 4 a 2, na tarde desta ter\u00e7a-feira (6) no est\u00e1dio Vel\u00f3drome, em Marselha, em confronto v\u00e1lido pelas semifinais [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5329,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1082],"tags":[164,203,1075,1093],"class_list":["post-5328","post","type-post","status-publish","format-standard","has-post-thumbnail","category-olimpiadas-2024","tag-brasil","tag-futebol-feminino","tag-olimpiadas-2024","tag-paris"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brasil derrota Espanha e garante lugar na final do futebol feminino - Maetinga Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maetinganoticias.com\/index.php\/2024\/08\/06\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brasil derrota Espanha e garante lugar na final do futebol feminino - Maetinga Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"Sele\u00e7\u00e3o brasileira joga bem e derrota campe\u00e3s do mundo por 4 a 2 O Brasil garantiu a classifica\u00e7\u00e3o para a decis\u00e3o do torneio de futebol feminino dos Jogos Ol\u00edmpicos de Paris (Fran\u00e7a) ap\u00f3s derrotar a Espanha por 4 a 2, na tarde desta ter\u00e7a-feira (6) no est\u00e1dio Vel\u00f3drome, em Marselha, em confronto v\u00e1lido pelas semifinais [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maetinganoticias.com\/index.php\/2024\/08\/06\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\/\" \/>\n<meta property=\"og:site_name\" content=\"Maetinga Not\u00edcias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-07T00:10:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-07T00:10:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-06-at-21.10.33.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1043\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maetinga Not\u00edcias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maetinga Not\u00edcias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2024\\\/08\\\/06\\\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2024\\\/08\\\/06\\\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\\\/\"},\"author\":{\"name\":\"Maetinga Not\u00edcias\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#\\\/schema\\\/person\\\/968cf95e67a6810fc7fb35bbc9016962\"},\"headline\":\"Brasil derrota Espanha e garante lugar na final do futebol feminino\",\"datePublished\":\"2024-08-07T00:10:58+00:00\",\"dateModified\":\"2024-08-07T00:10:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2024\\\/08\\\/06\\\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\\\/\"},\"wordCount\":489,\"commentCount\":137,\"publisher\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2024\\\/08\\\/06\\\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/WhatsApp-Image-2024-08-06-at-21.10.33.jpeg\",\"keywords\":[\"BRASIL\",\"FUTEBOL FEMININO\",\"OLIMP\u00cdADAS 2024\",\"PARIS\"],\"articleSection\":[\"OLIMPIADAS 2024\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2024\\\/08\\\/06\\\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2024\\\/08\\\/06\\\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\\\/\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2024\\\/08\\\/06\\\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\\\/\",\"name\":\"Brasil derrota Espanha e garante lugar na final do futebol feminino - Maetinga Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2024\\\/08\\\/06\\\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2024\\\/08\\\/06\\\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/WhatsApp-Image-2024-08-06-at-21.10.33.jpeg\",\"datePublished\":\"2024-08-07T00:10:58+00:00\",\"dateModified\":\"2024-08-07T00:10:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2024\\\/08\\\/06\\\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2024\\\/08\\\/06\\\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2024\\\/08\\\/06\\\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/WhatsApp-Image-2024-08-06-at-21.10.33.jpeg\",\"contentUrl\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/WhatsApp-Image-2024-08-06-at-21.10.33.jpeg\",\"width\":1043,\"height\":670,\"caption\":\"Olimp\u00edadas de Paris 2024 - Futebol - Semifinal Feminina - Brasil x Espanha. 06\\\/08\\\/2024. (Foto: REUTERS\\\/Andrew Boyers)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2024\\\/08\\\/06\\\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/maetinganoticias.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brasil derrota Espanha e garante lugar na final do futebol feminino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#website\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/\",\"name\":\"Maetinga Not\u00edcias\",\"description\":\"A Voz do Interior Baiano!\",\"publisher\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maetinganoticias.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#organization\",\"name\":\"Maetinga Not\u00edcias\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-cropped-cropped-BUSINESS-3-42-1.png\",\"contentUrl\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-cropped-cropped-BUSINESS-3-42-1.png\",\"width\":485,\"height\":109,\"caption\":\"Maetinga Not\u00edcias\"},\"image\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#\\\/schema\\\/person\\\/968cf95e67a6810fc7fb35bbc9016962\",\"name\":\"Maetinga Not\u00edcias\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g\",\"caption\":\"Maetinga Not\u00edcias\"},\"description\":\"A voz do Interior Baiano!\",\"sameAs\":[\"https:\\\/\\\/maetinganoticias.com\",\"https:\\\/\\\/www.instagram.com\\\/blogmaetinganoticias\\\/\"],\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/author\\\/carlosvianna13\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brasil derrota Espanha e garante lugar na final do futebol feminino - Maetinga Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maetinganoticias.com\/index.php\/2024\/08\/06\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\/","og_locale":"pt_BR","og_type":"article","og_title":"Brasil derrota Espanha e garante lugar na final do futebol feminino - Maetinga Not\u00edcias","og_description":"Sele\u00e7\u00e3o brasileira joga bem e derrota campe\u00e3s do mundo por 4 a 2 O Brasil garantiu a classifica\u00e7\u00e3o para a decis\u00e3o do torneio de futebol feminino dos Jogos Ol\u00edmpicos de Paris (Fran\u00e7a) ap\u00f3s derrotar a Espanha por 4 a 2, na tarde desta ter\u00e7a-feira (6) no est\u00e1dio Vel\u00f3drome, em Marselha, em confronto v\u00e1lido pelas semifinais [&hellip;]","og_url":"https:\/\/maetinganoticias.com\/index.php\/2024\/08\/06\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\/","og_site_name":"Maetinga Not\u00edcias","article_published_time":"2024-08-07T00:10:58+00:00","article_modified_time":"2024-08-07T00:10:59+00:00","og_image":[{"width":1043,"height":670,"url":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-06-at-21.10.33.jpeg","type":"image\/jpeg"}],"author":"Maetinga Not\u00edcias","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Maetinga Not\u00edcias","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/maetinganoticias.com\/index.php\/2024\/08\/06\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\/#article","isPartOf":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2024\/08\/06\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\/"},"author":{"name":"Maetinga Not\u00edcias","@id":"https:\/\/maetinganoticias.com\/#\/schema\/person\/968cf95e67a6810fc7fb35bbc9016962"},"headline":"Brasil derrota Espanha e garante lugar na final do futebol feminino","datePublished":"2024-08-07T00:10:58+00:00","dateModified":"2024-08-07T00:10:59+00:00","mainEntityOfPage":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2024\/08\/06\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\/"},"wordCount":489,"commentCount":137,"publisher":{"@id":"https:\/\/maetinganoticias.com\/#organization"},"image":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2024\/08\/06\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\/#primaryimage"},"thumbnailUrl":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-06-at-21.10.33.jpeg","keywords":["BRASIL","FUTEBOL FEMININO","OLIMP\u00cdADAS 2024","PARIS"],"articleSection":["OLIMPIADAS 2024"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maetinganoticias.com\/index.php\/2024\/08\/06\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maetinganoticias.com\/index.php\/2024\/08\/06\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\/","url":"https:\/\/maetinganoticias.com\/index.php\/2024\/08\/06\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\/","name":"Brasil derrota Espanha e garante lugar na final do futebol feminino - Maetinga Not\u00edcias","isPartOf":{"@id":"https:\/\/maetinganoticias.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2024\/08\/06\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\/#primaryimage"},"image":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2024\/08\/06\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\/#primaryimage"},"thumbnailUrl":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-06-at-21.10.33.jpeg","datePublished":"2024-08-07T00:10:58+00:00","dateModified":"2024-08-07T00:10:59+00:00","breadcrumb":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2024\/08\/06\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maetinganoticias.com\/index.php\/2024\/08\/06\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maetinganoticias.com\/index.php\/2024\/08\/06\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\/#primaryimage","url":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-06-at-21.10.33.jpeg","contentUrl":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-06-at-21.10.33.jpeg","width":1043,"height":670,"caption":"Olimp\u00edadas de Paris 2024 - Futebol - Semifinal Feminina - Brasil x Espanha. 06\/08\/2024. (Foto: REUTERS\/Andrew Boyers)"},{"@type":"BreadcrumbList","@id":"https:\/\/maetinganoticias.com\/index.php\/2024\/08\/06\/brasil-derrota-espanha-e-garante-lugar-na-final-do-futebol-feminino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/maetinganoticias.com\/"},{"@type":"ListItem","position":2,"name":"Brasil derrota Espanha e garante lugar na final do futebol feminino"}]},{"@type":"WebSite","@id":"https:\/\/maetinganoticias.com\/#website","url":"https:\/\/maetinganoticias.com\/","name":"Maetinga Not\u00edcias","description":"A Voz do Interior Baiano!","publisher":{"@id":"https:\/\/maetinganoticias.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maetinganoticias.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/maetinganoticias.com\/#organization","name":"Maetinga Not\u00edcias","url":"https:\/\/maetinganoticias.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maetinganoticias.com\/#\/schema\/logo\/image\/","url":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/07\/cropped-cropped-cropped-cropped-BUSINESS-3-42-1.png","contentUrl":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/07\/cropped-cropped-cropped-cropped-BUSINESS-3-42-1.png","width":485,"height":109,"caption":"Maetinga Not\u00edcias"},"image":{"@id":"https:\/\/maetinganoticias.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/maetinganoticias.com\/#\/schema\/person\/968cf95e67a6810fc7fb35bbc9016962","name":"Maetinga Not\u00edcias","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g","caption":"Maetinga Not\u00edcias"},"description":"A voz do Interior Baiano!","sameAs":["https:\/\/maetinganoticias.com","https:\/\/www.instagram.com\/blogmaetinganoticias\/"],"url":"https:\/\/maetinganoticias.com\/index.php\/author\/carlosvianna13\/"}]}},"_links":{"self":[{"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/5328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=5328"}],"version-history":[{"count":1,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/5328\/revisions"}],"predecessor-version":[{"id":5330,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/5328\/revisions\/5330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/media\/5329"}],"wp:attachment":[{"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=5328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=5328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=5328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}