{"id":2030,"date":"2023-11-27T12:50:40","date_gmt":"2023-11-27T15:50:40","guid":{"rendered":"https:\/\/maetinganoticias.com\/?p=2030"},"modified":"2023-11-27T12:50:41","modified_gmt":"2023-11-27T15:50:41","slug":"comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez","status":"publish","type":"post","link":"https:\/\/maetinganoticias.com\/index.php\/2023\/11\/27\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\/","title":{"rendered":"Comitiva de cavaleiros de Maetinga visitam gruta da Mangabeira pela 6\u00aa vez"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nesse \u00faltimo final de semana a Comitiva de Cavaleiros &#8220;100 P\u00e1rea&#8221; da cidade de Maetinga no sudoeste baiano, marcou presen\u00e7a na Gruta da Mangabeira que fica localizada na cidade de Itua\u00e7u na Chapada Diamantina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os Cavaleiros marcharam cerca de 140 Km com destino a tradicional gruta que recebe milhares de turistas durante todo o ano.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/11\/7b5b51af-0c4c-4064-8c4d-d2c5e6ffdc31-1024x768.jpg\" alt=\"\" class=\"wp-image-2031\" srcset=\"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/11\/7b5b51af-0c4c-4064-8c4d-d2c5e6ffdc31-1024x768.jpg 1024w, https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/11\/7b5b51af-0c4c-4064-8c4d-d2c5e6ffdc31-300x225.jpg 300w, https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/11\/7b5b51af-0c4c-4064-8c4d-d2c5e6ffdc31-768x576.jpg 768w, https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/11\/7b5b51af-0c4c-4064-8c4d-d2c5e6ffdc31-1536x1152.jpg 1536w, https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/11\/7b5b51af-0c4c-4064-8c4d-d2c5e6ffdc31-2048x1536.jpg 2048w, https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/11\/7b5b51af-0c4c-4064-8c4d-d2c5e6ffdc31-150x113.jpg 150w, https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/11\/7b5b51af-0c4c-4064-8c4d-d2c5e6ffdc31-696x522.jpg 696w, https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/11\/7b5b51af-0c4c-4064-8c4d-d2c5e6ffdc31-1068x801.jpg 1068w, https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/11\/7b5b51af-0c4c-4064-8c4d-d2c5e6ffdc31-1920x1440.jpg 1920w, https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/11\/7b5b51af-0c4c-4064-8c4d-d2c5e6ffdc31-560x420.jpg 560w, https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/11\/7b5b51af-0c4c-4064-8c4d-d2c5e6ffdc31-80x60.jpg 80w, https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/11\/7b5b51af-0c4c-4064-8c4d-d2c5e6ffdc31-265x198.jpg 265w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 a 6\u00b0 vez que a comitiva visita a cidade da Chapada Diamantina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesse \u00faltimo final de semana a Comitiva de Cavaleiros &#8220;100 P\u00e1rea&#8221; da cidade de Maetinga no sudoeste baiano, marcou presen\u00e7a na Gruta da Mangabeira que fica localizada na cidade de Itua\u00e7u na Chapada Diamantina. Os Cavaleiros marcharam cerca de 140 Km com destino a tradicional gruta que recebe milhares de turistas durante todo o ano. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2032,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[6,1],"tags":[81,428,257,76,166,145,429],"class_list":["post-2030","post","type-post","status-publish","format-standard","has-post-thumbnail","category-maetinga","category-blog","tag-bahia","tag-cavaleiros","tag-cultura","tag-ituacu","tag-maetinga","tag-sudoeste-da-bahia","tag-tradicao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comitiva de cavaleiros de Maetinga visitam gruta da Mangabeira pela 6\u00aa vez - Maetinga Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maetinganoticias.com\/index.php\/2023\/11\/27\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comitiva de cavaleiros de Maetinga visitam gruta da Mangabeira pela 6\u00aa vez - Maetinga Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"Nesse \u00faltimo final de semana a Comitiva de Cavaleiros &#8220;100 P\u00e1rea&#8221; da cidade de Maetinga no sudoeste baiano, marcou presen\u00e7a na Gruta da Mangabeira que fica localizada na cidade de Itua\u00e7u na Chapada Diamantina. Os Cavaleiros marcharam cerca de 140 Km com destino a tradicional gruta que recebe milhares de turistas durante todo o ano. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maetinganoticias.com\/index.php\/2023\/11\/27\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\/\" \/>\n<meta property=\"og:site_name\" content=\"Maetinga Not\u00edcias\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-27T15:50:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-27T15:50:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/11\/d9fbbe1d-6c60-47c7-a352-5651209b4544-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maetinga Not\u00edcias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maetinga Not\u00edcias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2023\\\/11\\\/27\\\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2023\\\/11\\\/27\\\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\\\/\"},\"author\":{\"name\":\"Maetinga Not\u00edcias\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#\\\/schema\\\/person\\\/968cf95e67a6810fc7fb35bbc9016962\"},\"headline\":\"Comitiva de cavaleiros de Maetinga visitam gruta da Mangabeira pela 6\u00aa vez\",\"datePublished\":\"2023-11-27T15:50:40+00:00\",\"dateModified\":\"2023-11-27T15:50:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2023\\\/11\\\/27\\\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\\\/\"},\"wordCount\":78,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2023\\\/11\\\/27\\\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/d9fbbe1d-6c60-47c7-a352-5651209b4544-scaled.jpg\",\"keywords\":[\"BAHIA\",\"CAVALEIROS\",\"CULTURA\",\"ITUA\u00c7U\",\"MAETINGA\",\"SUDOESTE DA BAHIA\",\"TRADI\u00c7\u00c3O\"],\"articleSection\":[\"Maetinga\",\"Regi\u00e3o\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2023\\\/11\\\/27\\\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2023\\\/11\\\/27\\\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\\\/\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2023\\\/11\\\/27\\\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\\\/\",\"name\":\"Comitiva de cavaleiros de Maetinga visitam gruta da Mangabeira pela 6\u00aa vez - Maetinga Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2023\\\/11\\\/27\\\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2023\\\/11\\\/27\\\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/d9fbbe1d-6c60-47c7-a352-5651209b4544-scaled.jpg\",\"datePublished\":\"2023-11-27T15:50:40+00:00\",\"dateModified\":\"2023-11-27T15:50:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2023\\\/11\\\/27\\\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2023\\\/11\\\/27\\\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2023\\\/11\\\/27\\\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/d9fbbe1d-6c60-47c7-a352-5651209b4544-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/d9fbbe1d-6c60-47c7-a352-5651209b4544-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2023\\\/11\\\/27\\\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/maetinganoticias.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comitiva de cavaleiros de Maetinga visitam gruta da Mangabeira pela 6\u00aa vez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#website\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/\",\"name\":\"Maetinga Not\u00edcias\",\"description\":\"A Voz do Interior Baiano!\",\"publisher\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maetinganoticias.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#organization\",\"name\":\"Maetinga Not\u00edcias\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-cropped-cropped-BUSINESS-3-42-1.png\",\"contentUrl\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-cropped-cropped-BUSINESS-3-42-1.png\",\"width\":485,\"height\":109,\"caption\":\"Maetinga Not\u00edcias\"},\"image\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#\\\/schema\\\/person\\\/968cf95e67a6810fc7fb35bbc9016962\",\"name\":\"Maetinga Not\u00edcias\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g\",\"caption\":\"Maetinga Not\u00edcias\"},\"description\":\"A voz do Interior Baiano!\",\"sameAs\":[\"https:\\\/\\\/maetinganoticias.com\",\"https:\\\/\\\/www.instagram.com\\\/blogmaetinganoticias\\\/\"],\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/author\\\/carlosvianna13\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comitiva de cavaleiros de Maetinga visitam gruta da Mangabeira pela 6\u00aa vez - Maetinga Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maetinganoticias.com\/index.php\/2023\/11\/27\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\/","og_locale":"pt_BR","og_type":"article","og_title":"Comitiva de cavaleiros de Maetinga visitam gruta da Mangabeira pela 6\u00aa vez - Maetinga Not\u00edcias","og_description":"Nesse \u00faltimo final de semana a Comitiva de Cavaleiros &#8220;100 P\u00e1rea&#8221; da cidade de Maetinga no sudoeste baiano, marcou presen\u00e7a na Gruta da Mangabeira que fica localizada na cidade de Itua\u00e7u na Chapada Diamantina. Os Cavaleiros marcharam cerca de 140 Km com destino a tradicional gruta que recebe milhares de turistas durante todo o ano. [&hellip;]","og_url":"https:\/\/maetinganoticias.com\/index.php\/2023\/11\/27\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\/","og_site_name":"Maetinga Not\u00edcias","article_published_time":"2023-11-27T15:50:40+00:00","article_modified_time":"2023-11-27T15:50:41+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/11\/d9fbbe1d-6c60-47c7-a352-5651209b4544-scaled.jpg","type":"image\/jpeg"}],"author":"Maetinga Not\u00edcias","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Maetinga Not\u00edcias","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/maetinganoticias.com\/index.php\/2023\/11\/27\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\/#article","isPartOf":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2023\/11\/27\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\/"},"author":{"name":"Maetinga Not\u00edcias","@id":"https:\/\/maetinganoticias.com\/#\/schema\/person\/968cf95e67a6810fc7fb35bbc9016962"},"headline":"Comitiva de cavaleiros de Maetinga visitam gruta da Mangabeira pela 6\u00aa vez","datePublished":"2023-11-27T15:50:40+00:00","dateModified":"2023-11-27T15:50:41+00:00","mainEntityOfPage":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2023\/11\/27\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\/"},"wordCount":78,"commentCount":0,"publisher":{"@id":"https:\/\/maetinganoticias.com\/#organization"},"image":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2023\/11\/27\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\/#primaryimage"},"thumbnailUrl":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/11\/d9fbbe1d-6c60-47c7-a352-5651209b4544-scaled.jpg","keywords":["BAHIA","CAVALEIROS","CULTURA","ITUA\u00c7U","MAETINGA","SUDOESTE DA BAHIA","TRADI\u00c7\u00c3O"],"articleSection":["Maetinga","Regi\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maetinganoticias.com\/index.php\/2023\/11\/27\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maetinganoticias.com\/index.php\/2023\/11\/27\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\/","url":"https:\/\/maetinganoticias.com\/index.php\/2023\/11\/27\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\/","name":"Comitiva de cavaleiros de Maetinga visitam gruta da Mangabeira pela 6\u00aa vez - Maetinga Not\u00edcias","isPartOf":{"@id":"https:\/\/maetinganoticias.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2023\/11\/27\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\/#primaryimage"},"image":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2023\/11\/27\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\/#primaryimage"},"thumbnailUrl":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/11\/d9fbbe1d-6c60-47c7-a352-5651209b4544-scaled.jpg","datePublished":"2023-11-27T15:50:40+00:00","dateModified":"2023-11-27T15:50:41+00:00","breadcrumb":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2023\/11\/27\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maetinganoticias.com\/index.php\/2023\/11\/27\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maetinganoticias.com\/index.php\/2023\/11\/27\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\/#primaryimage","url":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/11\/d9fbbe1d-6c60-47c7-a352-5651209b4544-scaled.jpg","contentUrl":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/11\/d9fbbe1d-6c60-47c7-a352-5651209b4544-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/maetinganoticias.com\/index.php\/2023\/11\/27\/comitiva-de-cavaleiros-de-maetinga-visitam-gruta-da-mangabeira-pela-6a-vez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/maetinganoticias.com\/"},{"@type":"ListItem","position":2,"name":"Comitiva de cavaleiros de Maetinga visitam gruta da Mangabeira pela 6\u00aa vez"}]},{"@type":"WebSite","@id":"https:\/\/maetinganoticias.com\/#website","url":"https:\/\/maetinganoticias.com\/","name":"Maetinga Not\u00edcias","description":"A Voz do Interior Baiano!","publisher":{"@id":"https:\/\/maetinganoticias.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maetinganoticias.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/maetinganoticias.com\/#organization","name":"Maetinga Not\u00edcias","url":"https:\/\/maetinganoticias.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maetinganoticias.com\/#\/schema\/logo\/image\/","url":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/07\/cropped-cropped-cropped-cropped-BUSINESS-3-42-1.png","contentUrl":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/07\/cropped-cropped-cropped-cropped-BUSINESS-3-42-1.png","width":485,"height":109,"caption":"Maetinga Not\u00edcias"},"image":{"@id":"https:\/\/maetinganoticias.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/maetinganoticias.com\/#\/schema\/person\/968cf95e67a6810fc7fb35bbc9016962","name":"Maetinga Not\u00edcias","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g","caption":"Maetinga Not\u00edcias"},"description":"A voz do Interior Baiano!","sameAs":["https:\/\/maetinganoticias.com","https:\/\/www.instagram.com\/blogmaetinganoticias\/"],"url":"https:\/\/maetinganoticias.com\/index.php\/author\/carlosvianna13\/"}]}},"_links":{"self":[{"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/2030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=2030"}],"version-history":[{"count":1,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/2030\/revisions"}],"predecessor-version":[{"id":2033,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/2030\/revisions\/2033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/media\/2032"}],"wp:attachment":[{"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=2030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=2030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=2030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}