{"id":13045,"date":"2026-07-17T15:49:09","date_gmt":"2026-07-17T18:49:09","guid":{"rendered":"https:\/\/maetinganoticias.com\/?p=13045"},"modified":"2026-07-17T15:49:10","modified_gmt":"2026-07-17T18:49:10","slug":"senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres","status":"publish","type":"post","link":"https:\/\/maetinganoticias.com\/index.php\/2026\/07\/17\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\/","title":{"rendered":"Senado aprova projeto que criminaliza divulga\u00e7\u00e3o n\u00e3o autorizada de imagens de v\u00edtimas de crimes, acidentes e cad\u00e1veres"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O Plen\u00e1rio do Senado aprovou nesta quarta-feira (15) o projeto de lei que criminaliza o registro e a divulga\u00e7\u00e3o n\u00e3o autorizada de imagens que identifiquem v\u00edtimas de crimes ou acidentes, assim como imagens de cad\u00e1veres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O projeto (PL 1.242\/2026), de autoria da deputada federal Laura Carneiro (PSD-RJ), recebeu parecer favor\u00e1vel do senador Marcelo Castro (MDB-PI). Como o texto foi alterado no Senado, a mat\u00e9ria retornar\u00e1 \u00e0 C\u00e2mara, onde teve origem, para nova an\u00e1lise.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A proposta altera o C\u00f3digo Civil para ampliar a prote\u00e7\u00e3o da honra e da imagem das v\u00edtimas. Tamb\u00e9m modifica o C\u00f3digo Penal para tipificar como crime a divulga\u00e7\u00e3o, sem justa causa, desse material.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O texto prev\u00ea exce\u00e7\u00f5es quando a divulga\u00e7\u00e3o for necess\u00e1ria para a Justi\u00e7a, para atender a interesse p\u00fablico devidamente justificado ou quando houver o consentimento da v\u00edtima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, a vers\u00e3o aprovada no Senado reduz a pena prevista na vers\u00e3o original do projeto para os crimes em quest\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O texto que veio da C\u00e2mara previa reclus\u00e3o de 1 a 3 anos, al\u00e9m de multa. O parecer de Marcelo Castro reduziu a pena para deten\u00e7\u00e3o de seis meses a dois anos, al\u00e9m de multa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A previs\u00e3o inicial era que essa mat\u00e9ria fosse votada pelo Plen\u00e1rio do Senado na quinta-feira (16), mas a vota\u00e7\u00e3o foi antecipada em um dia pelo presidente da Casa, Davi Alcolumbre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cr\u00e9ditos: Senado federal<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Plen\u00e1rio do Senado aprovou nesta quarta-feira (15) o projeto de lei que criminaliza o registro e a divulga\u00e7\u00e3o n\u00e3o autorizada de imagens que identifiquem v\u00edtimas de crimes ou acidentes, assim como imagens de cad\u00e1veres. O projeto (PL 1.242\/2026), de autoria da deputada federal Laura Carneiro (PSD-RJ), recebeu parecer favor\u00e1vel do senador Marcelo Castro (MDB-PI). [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13046,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[29,1],"tags":[],"class_list":["post-13045","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Senado aprova projeto que criminaliza divulga\u00e7\u00e3o n\u00e3o autorizada de imagens de v\u00edtimas de crimes, acidentes e cad\u00e1veres - Maetinga Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maetinganoticias.com\/index.php\/2026\/07\/17\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Senado aprova projeto que criminaliza divulga\u00e7\u00e3o n\u00e3o autorizada de imagens de v\u00edtimas de crimes, acidentes e cad\u00e1veres - Maetinga Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"O Plen\u00e1rio do Senado aprovou nesta quarta-feira (15) o projeto de lei que criminaliza o registro e a divulga\u00e7\u00e3o n\u00e3o autorizada de imagens que identifiquem v\u00edtimas de crimes ou acidentes, assim como imagens de cad\u00e1veres. O projeto (PL 1.242\/2026), de autoria da deputada federal Laura Carneiro (PSD-RJ), recebeu parecer favor\u00e1vel do senador Marcelo Castro (MDB-PI). [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maetinganoticias.com\/index.php\/2026\/07\/17\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\/\" \/>\n<meta property=\"og:site_name\" content=\"Maetinga Not\u00edcias\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-17T18:49:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-17T18:49:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-17-at-15.48.48.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"547\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maetinga Not\u00edcias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maetinga Not\u00edcias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2026\\\/07\\\/17\\\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2026\\\/07\\\/17\\\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\\\/\"},\"author\":{\"name\":\"Maetinga Not\u00edcias\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#\\\/schema\\\/person\\\/968cf95e67a6810fc7fb35bbc9016962\"},\"headline\":\"Senado aprova projeto que criminaliza divulga\u00e7\u00e3o n\u00e3o autorizada de imagens de v\u00edtimas de crimes, acidentes e cad\u00e1veres\",\"datePublished\":\"2026-07-17T18:49:09+00:00\",\"dateModified\":\"2026-07-17T18:49:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2026\\\/07\\\/17\\\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\\\/\"},\"wordCount\":271,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2026\\\/07\\\/17\\\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-17-at-15.48.48.jpeg\",\"articleSection\":[\"Brasil\",\"Regi\u00e3o\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2026\\\/07\\\/17\\\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2026\\\/07\\\/17\\\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\\\/\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2026\\\/07\\\/17\\\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\\\/\",\"name\":\"Senado aprova projeto que criminaliza divulga\u00e7\u00e3o n\u00e3o autorizada de imagens de v\u00edtimas de crimes, acidentes e cad\u00e1veres - Maetinga Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2026\\\/07\\\/17\\\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2026\\\/07\\\/17\\\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-17-at-15.48.48.jpeg\",\"datePublished\":\"2026-07-17T18:49:09+00:00\",\"dateModified\":\"2026-07-17T18:49:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2026\\\/07\\\/17\\\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2026\\\/07\\\/17\\\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2026\\\/07\\\/17\\\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-17-at-15.48.48.jpeg\",\"contentUrl\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-17-at-15.48.48.jpeg\",\"width\":547,\"height\":365,\"caption\":\"Foto: Thain\u00e1 Salviato\\\/R\u00e1dio Senado (com aux\u00edlio de IA)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/2026\\\/07\\\/17\\\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/maetinganoticias.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Senado aprova projeto que criminaliza divulga\u00e7\u00e3o n\u00e3o autorizada de imagens de v\u00edtimas de crimes, acidentes e cad\u00e1veres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#website\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/\",\"name\":\"Maetinga Not\u00edcias\",\"description\":\"A Voz do Interior Baiano!\",\"publisher\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maetinganoticias.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#organization\",\"name\":\"Maetinga Not\u00edcias\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-cropped-cropped-BUSINESS-3-42-1.png\",\"contentUrl\":\"https:\\\/\\\/maetinganoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-cropped-cropped-cropped-BUSINESS-3-42-1.png\",\"width\":485,\"height\":109,\"caption\":\"Maetinga Not\u00edcias\"},\"image\":{\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maetinganoticias.com\\\/#\\\/schema\\\/person\\\/968cf95e67a6810fc7fb35bbc9016962\",\"name\":\"Maetinga Not\u00edcias\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g\",\"caption\":\"Maetinga Not\u00edcias\"},\"description\":\"A voz do Interior Baiano!\",\"sameAs\":[\"https:\\\/\\\/maetinganoticias.com\",\"https:\\\/\\\/www.instagram.com\\\/blogmaetinganoticias\\\/\"],\"url\":\"https:\\\/\\\/maetinganoticias.com\\\/index.php\\\/author\\\/carlosvianna13\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Senado aprova projeto que criminaliza divulga\u00e7\u00e3o n\u00e3o autorizada de imagens de v\u00edtimas de crimes, acidentes e cad\u00e1veres - Maetinga Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maetinganoticias.com\/index.php\/2026\/07\/17\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\/","og_locale":"pt_BR","og_type":"article","og_title":"Senado aprova projeto que criminaliza divulga\u00e7\u00e3o n\u00e3o autorizada de imagens de v\u00edtimas de crimes, acidentes e cad\u00e1veres - Maetinga Not\u00edcias","og_description":"O Plen\u00e1rio do Senado aprovou nesta quarta-feira (15) o projeto de lei que criminaliza o registro e a divulga\u00e7\u00e3o n\u00e3o autorizada de imagens que identifiquem v\u00edtimas de crimes ou acidentes, assim como imagens de cad\u00e1veres. O projeto (PL 1.242\/2026), de autoria da deputada federal Laura Carneiro (PSD-RJ), recebeu parecer favor\u00e1vel do senador Marcelo Castro (MDB-PI). [&hellip;]","og_url":"https:\/\/maetinganoticias.com\/index.php\/2026\/07\/17\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\/","og_site_name":"Maetinga Not\u00edcias","article_published_time":"2026-07-17T18:49:09+00:00","article_modified_time":"2026-07-17T18:49:10+00:00","og_image":[{"width":547,"height":365,"url":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-17-at-15.48.48.jpeg","type":"image\/jpeg"}],"author":"Maetinga Not\u00edcias","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Maetinga Not\u00edcias","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/maetinganoticias.com\/index.php\/2026\/07\/17\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\/#article","isPartOf":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2026\/07\/17\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\/"},"author":{"name":"Maetinga Not\u00edcias","@id":"https:\/\/maetinganoticias.com\/#\/schema\/person\/968cf95e67a6810fc7fb35bbc9016962"},"headline":"Senado aprova projeto que criminaliza divulga\u00e7\u00e3o n\u00e3o autorizada de imagens de v\u00edtimas de crimes, acidentes e cad\u00e1veres","datePublished":"2026-07-17T18:49:09+00:00","dateModified":"2026-07-17T18:49:10+00:00","mainEntityOfPage":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2026\/07\/17\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\/"},"wordCount":271,"commentCount":4,"publisher":{"@id":"https:\/\/maetinganoticias.com\/#organization"},"image":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2026\/07\/17\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\/#primaryimage"},"thumbnailUrl":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-17-at-15.48.48.jpeg","articleSection":["Brasil","Regi\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maetinganoticias.com\/index.php\/2026\/07\/17\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maetinganoticias.com\/index.php\/2026\/07\/17\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\/","url":"https:\/\/maetinganoticias.com\/index.php\/2026\/07\/17\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\/","name":"Senado aprova projeto que criminaliza divulga\u00e7\u00e3o n\u00e3o autorizada de imagens de v\u00edtimas de crimes, acidentes e cad\u00e1veres - Maetinga Not\u00edcias","isPartOf":{"@id":"https:\/\/maetinganoticias.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2026\/07\/17\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\/#primaryimage"},"image":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2026\/07\/17\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\/#primaryimage"},"thumbnailUrl":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-17-at-15.48.48.jpeg","datePublished":"2026-07-17T18:49:09+00:00","dateModified":"2026-07-17T18:49:10+00:00","breadcrumb":{"@id":"https:\/\/maetinganoticias.com\/index.php\/2026\/07\/17\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maetinganoticias.com\/index.php\/2026\/07\/17\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maetinganoticias.com\/index.php\/2026\/07\/17\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\/#primaryimage","url":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-17-at-15.48.48.jpeg","contentUrl":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-17-at-15.48.48.jpeg","width":547,"height":365,"caption":"Foto: Thain\u00e1 Salviato\/R\u00e1dio Senado (com aux\u00edlio de IA)"},{"@type":"BreadcrumbList","@id":"https:\/\/maetinganoticias.com\/index.php\/2026\/07\/17\/senado-aprova-projeto-que-criminaliza-divulgacao-nao-autorizada-de-imagens-de-vitimas-de-crimes-acidentes-e-cadaveres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/maetinganoticias.com\/"},{"@type":"ListItem","position":2,"name":"Senado aprova projeto que criminaliza divulga\u00e7\u00e3o n\u00e3o autorizada de imagens de v\u00edtimas de crimes, acidentes e cad\u00e1veres"}]},{"@type":"WebSite","@id":"https:\/\/maetinganoticias.com\/#website","url":"https:\/\/maetinganoticias.com\/","name":"Maetinga Not\u00edcias","description":"A Voz do Interior Baiano!","publisher":{"@id":"https:\/\/maetinganoticias.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maetinganoticias.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/maetinganoticias.com\/#organization","name":"Maetinga Not\u00edcias","url":"https:\/\/maetinganoticias.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maetinganoticias.com\/#\/schema\/logo\/image\/","url":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/07\/cropped-cropped-cropped-cropped-BUSINESS-3-42-1.png","contentUrl":"https:\/\/maetinganoticias.com\/wp-content\/uploads\/2023\/07\/cropped-cropped-cropped-cropped-BUSINESS-3-42-1.png","width":485,"height":109,"caption":"Maetinga Not\u00edcias"},"image":{"@id":"https:\/\/maetinganoticias.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/maetinganoticias.com\/#\/schema\/person\/968cf95e67a6810fc7fb35bbc9016962","name":"Maetinga Not\u00edcias","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32e078313a5ca37a6c8d44e716ed4f9e87ecfde7222d2b88a1424bd49654f187?s=96&d=mm&r=g","caption":"Maetinga Not\u00edcias"},"description":"A voz do Interior Baiano!","sameAs":["https:\/\/maetinganoticias.com","https:\/\/www.instagram.com\/blogmaetinganoticias\/"],"url":"https:\/\/maetinganoticias.com\/index.php\/author\/carlosvianna13\/"}]}},"_links":{"self":[{"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/13045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=13045"}],"version-history":[{"count":1,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/13045\/revisions"}],"predecessor-version":[{"id":13047,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/13045\/revisions\/13047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/media\/13046"}],"wp:attachment":[{"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=13045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=13045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maetinganoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=13045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}